{"id":15458,"date":"2018-07-17T22:06:29","date_gmt":"2018-07-17T20:06:29","guid":{"rendered":"https:\/\/costablancaup.com\/class\/cine-bajo-la-luna-del-lado-del-verano-2\/"},"modified":"2018-07-19T11:28:36","modified_gmt":"2018-07-19T09:28:36","slug":"cine-bajo-la-luna-abracabra","status":"publish","type":"class","link":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/","title":{"rendered":"Cine bajo la luna: \u00abAbracabra\u00bb"},"content":{"rendered":"<p>El Festival de Cine de Alicante ha puesto en marcha una nueva iniciativa que bajo el t\u00edtulo de \u2018Cine Bajo La Luna\u2019, recoge una propuesta que une cultura y gastronom\u00eda al aire libre.<\/p>\n<p>Este nuevo ciclo de cine incluye un men\u00fa cerrado adem\u00e1s de las proyecciones al aire libre por un precio de 29 euros. Adem\u00e1s, se puede asistir a la proyecci\u00f3n y solo adquirir una consumici\u00f3n por 9 euros. La cena dar\u00e1 comienzo a las 21.15 horas y la proyecci\u00f3n de la pel\u00edcula a las 22:30 horas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/abracabra.jpg\" alt=\"Cine bajo la luna: Abracabra\" width=\"250\" height=\"394\" class=\"alignleft size-full wp-image-15451\" \/><\/p>\n<p>El ciclo se cerrar\u00e1 el d\u00eda 31 de agosto con la cuarta proyecci\u00f3n, la de la comedia \u00abAbracabra\u00bb, dirigida por Pablo Bergert y protagonizada por Maribel Verd\u00fa, Antonio de la Torre y Jos\u00e9 Mota. La pel\u00edcula cuenta la historia de Carmen (Maribel Verd\u00fa), un ama de casa del barrio madrile\u00f1o de Carabanchel, que descubre un d\u00eda que su marido, Carlos (Antonio de la Torre), parece estar pose\u00eddo por un esp\u00edritu maligno. Ah\u00ed empieza una exhaustiva investigaci\u00f3n, entre terror\u00edfica y disparatada, para intentar recuperarlo.<\/p>\n<p>Se recomienda reservar por tel\u00e9fono en el 965 15 95 24 \/ 608 68 61 77.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Festival de Cine de Alicante ha puesto en marcha una nueva iniciativa que bajo el t\u00edtulo de \u2018Cine Bajo La Luna\u2019, recoge una propuesta que une cultura y gastronom\u00eda al aire libre. Este nuevo ciclo de cine incluye un men\u00fa cerrado adem\u00e1s de las proyecciones al aire libre por un precio de 29 euros. Adem\u00e1s, se puede asistir a la proyecci\u00f3n y solo adquirir una consumici\u00f3n por 9 euros. La cena dar\u00e1 comienzo a las 21.15 horas y la proyecci\u00f3n de la pel\u00edcula a las 22:30 horas. El ciclo se cerrar\u00e1 el d\u00eda 31 de agosto con la cuarta [&hellip;]<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[5077],"wcs-room":[5115],"wcs-instructor":[],"class_list":["post-15458","class","type-class","status-publish","hentry","wcs-type-cine","wcs-room-finca-casa-luna-alicante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cine bajo la luna: &quot;Abracabra&quot; - COSTA BLANCA UP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cine bajo la luna: &quot;Abracabra&quot; - COSTA BLANCA UP\" \/>\n<meta property=\"og:description\" content=\"El Festival de Cine de Alicante ha puesto en marcha una nueva iniciativa que bajo el t\u00edtulo de \u2018Cine Bajo La Luna\u2019, recoge una propuesta que une cultura y gastronom\u00eda al aire libre. Este nuevo ciclo de cine incluye un men\u00fa cerrado adem\u00e1s de las proyecciones al aire libre por un precio de 29 euros. Adem\u00e1s, se puede asistir a la proyecci\u00f3n y solo adquirir una consumici\u00f3n por 9 euros. La cena dar\u00e1 comienzo a las 21.15 horas y la proyecci\u00f3n de la pel\u00edcula a las 22:30 horas. El ciclo se cerrar\u00e1 el d\u00eda 31 de agosto con la cuarta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-19T09:28:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/abracabra.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/\",\"name\":\"Cine bajo la luna: \\\"Abracabra\\\" - COSTA BLANCA UP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/abracabra.jpg\",\"datePublished\":\"2018-07-17T20:06:29+00:00\",\"dateModified\":\"2018-07-19T09:28:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/abracabra.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/abracabra.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/cine-bajo-la-luna-abracabra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cine bajo la luna: \u00abAbracabra\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cine bajo la luna: \"Abracabra\" - COSTA BLANCA UP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/","og_locale":"es_ES","og_type":"article","og_title":"Cine bajo la luna: \"Abracabra\" - COSTA BLANCA UP","og_description":"El Festival de Cine de Alicante ha puesto en marcha una nueva iniciativa que bajo el t\u00edtulo de \u2018Cine Bajo La Luna\u2019, recoge una propuesta que une cultura y gastronom\u00eda al aire libre. Este nuevo ciclo de cine incluye un men\u00fa cerrado adem\u00e1s de las proyecciones al aire libre por un precio de 29 euros. Adem\u00e1s, se puede asistir a la proyecci\u00f3n y solo adquirir una consumici\u00f3n por 9 euros. La cena dar\u00e1 comienzo a las 21.15 horas y la proyecci\u00f3n de la pel\u00edcula a las 22:30 horas. El ciclo se cerrar\u00e1 el d\u00eda 31 de agosto con la cuarta [&hellip;]","og_url":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/","og_site_name":"COSTA BLANCA UP","article_modified_time":"2018-07-19T09:28:36+00:00","og_image":[{"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/abracabra.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/","url":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/","name":"Cine bajo la luna: \"Abracabra\" - COSTA BLANCA UP","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/abracabra.jpg","datePublished":"2018-07-17T20:06:29+00:00","dateModified":"2018-07-19T09:28:36+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/abracabra.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/abracabra.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/class\/cine-bajo-la-luna-abracabra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cine bajo la luna: \u00abAbracabra\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class\/15458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=15458"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-type?post=15458"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-room?post=15458"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-instructor?post=15458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}