{"id":17066,"date":"2018-09-12T11:33:58","date_gmt":"2018-09-12T09:33:58","guid":{"rendered":"https:\/\/costablancaup.com\/class\/circarte-2018-3-2-2\/"},"modified":"2018-09-12T12:08:20","modified_gmt":"2018-09-12T10:08:20","slug":"circarte-2018-5","status":"publish","type":"class","link":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/","title":{"rendered":"Circarte 2018"},"content":{"rendered":"<h3>\u00abCircarte\u00bb sigue expandi\u00e9ndose en ubicaciones y en actividades en su labor de impulso y promoci\u00f3n del circo contempor\u00e1neo y su acercamiento al p\u00fablico.<\/h3>\n<p>El programa de \u00abCircarte 2018\u00bb cuenta con cincuenta artistas de veinte compa\u00f1\u00edas locales, nacionales e internacionales que, a lo largo de tres semanas, mostrar\u00e1n sus espect\u00e1culos de las m\u00e1s variadas disciplinas: acrobacias de suelo, a\u00e9reas, en d\u00fao, malabares y manipulaci\u00f3n de objetos, contorsi\u00f3n, suspensi\u00f3n capilar, <em>clow<\/em>n o equilibrismo, y sus fusiones con la danza, el teatro y la m\u00fasica en directo.<\/p>\n<p>Aunque la mayor\u00eda de las actuaciones ser\u00e1n gratuitas o mediante el sistema <em>pay after show<\/em> (donde el p\u00fablico paga lo que considere tras el espect\u00e1culo), se necesita una reserva previa para los espect\u00e1culos de sala con un aforo limitado.<\/p>\n<h3>Programa<\/h3>\n<p>Viernes 21 en Alicante<\/p>\n<ul>\n<li>20.30h: EL CRUCE \u201cPunto y Coma\u201d \u2013 Teatro Arniches \u2013 Todos los p\u00fablicos \u2013 Entrada 4\u20ac\/10\u20ac \u2013 Duraci\u00f3n 50 minutos.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa.jpg\" alt=\"Circarte 2018: programa\" width=\"1024\" height=\"2742\" class=\"aligncenter size-full wp-image-17049\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa.jpg 1024w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa-112x300.jpg 112w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa-768x2057.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa-382x1024.jpg 382w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa-400x1071.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abCircarte\u00bb sigue expandi\u00e9ndose en ubicaciones y en actividades en su labor de impulso y promoci\u00f3n del circo contempor\u00e1neo y su acercamiento al p\u00fablico. El programa de \u00abCircarte 2018\u00bb cuenta con cincuenta artistas de veinte compa\u00f1\u00edas locales, nacionales e internacionales que, a lo largo de tres semanas, mostrar\u00e1n sus espect\u00e1culos de las m\u00e1s variadas disciplinas: acrobacias de suelo, a\u00e9reas, en d\u00fao, malabares y manipulaci\u00f3n de objetos, contorsi\u00f3n, suspensi\u00f3n capilar, clown o equilibrismo, y sus fusiones con la danza, el teatro y la m\u00fasica en directo. Aunque la mayor\u00eda de las actuaciones ser\u00e1n gratuitas o mediante el sistema pay after show (donde [&hellip;]<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[5042,5036],"wcs-room":[5342],"wcs-instructor":[],"class_list":["post-17066","class","type-class","status-publish","hentry","wcs-type-espectaculos","wcs-type-ninos","wcs-room-teatro-arniches-alicante"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Circarte 2018 - COSTA BLANCA UP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circarte 2018 - COSTA BLANCA UP\" \/>\n<meta property=\"og:description\" content=\"\u00abCircarte\u00bb sigue expandi\u00e9ndose en ubicaciones y en actividades en su labor de impulso y promoci\u00f3n del circo contempor\u00e1neo y su acercamiento al p\u00fablico. El programa de \u00abCircarte 2018\u00bb cuenta con cincuenta artistas de veinte compa\u00f1\u00edas locales, nacionales e internacionales que, a lo largo de tres semanas, mostrar\u00e1n sus espect\u00e1culos de las m\u00e1s variadas disciplinas: acrobacias de suelo, a\u00e9reas, en d\u00fao, malabares y manipulaci\u00f3n de objetos, contorsi\u00f3n, suspensi\u00f3n capilar, clown o equilibrismo, y sus fusiones con la danza, el teatro y la m\u00fasica en directo. Aunque la mayor\u00eda de las actuaciones ser\u00e1n gratuitas o mediante el sistema pay after show (donde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-12T10:08:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/\",\"name\":\"Circarte 2018 - COSTA BLANCA UP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/circarte-2018-programa.jpg\",\"datePublished\":\"2018-09-12T09:33:58+00:00\",\"dateModified\":\"2018-09-12T10:08:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/circarte-2018-programa.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/circarte-2018-programa.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/circarte-2018-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circarte 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Circarte 2018 - COSTA BLANCA UP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/","og_locale":"es_ES","og_type":"article","og_title":"Circarte 2018 - COSTA BLANCA UP","og_description":"\u00abCircarte\u00bb sigue expandi\u00e9ndose en ubicaciones y en actividades en su labor de impulso y promoci\u00f3n del circo contempor\u00e1neo y su acercamiento al p\u00fablico. El programa de \u00abCircarte 2018\u00bb cuenta con cincuenta artistas de veinte compa\u00f1\u00edas locales, nacionales e internacionales que, a lo largo de tres semanas, mostrar\u00e1n sus espect\u00e1culos de las m\u00e1s variadas disciplinas: acrobacias de suelo, a\u00e9reas, en d\u00fao, malabares y manipulaci\u00f3n de objetos, contorsi\u00f3n, suspensi\u00f3n capilar, clown o equilibrismo, y sus fusiones con la danza, el teatro y la m\u00fasica en directo. Aunque la mayor\u00eda de las actuaciones ser\u00e1n gratuitas o mediante el sistema pay after show (donde [&hellip;]","og_url":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/","og_site_name":"COSTA BLANCA UP","article_modified_time":"2018-09-12T10:08:20+00:00","og_image":[{"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/","url":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/","name":"Circarte 2018 - COSTA BLANCA UP","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa.jpg","datePublished":"2018-09-12T09:33:58+00:00","dateModified":"2018-09-12T10:08:20+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/09\/circarte-2018-programa.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/class\/circarte-2018-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Circarte 2018"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class\/17066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=17066"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-type?post=17066"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-room?post=17066"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-instructor?post=17066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}