{"id":39377,"date":"2020-01-15T09:47:22","date_gmt":"2020-01-15T08:47:22","guid":{"rendered":"https:\/\/costablancaup.com\/?post_type=class&#038;p=39377"},"modified":"2020-01-15T09:47:22","modified_gmt":"2020-01-15T08:47:22","slug":"ananda-dansa-atman-el-comiat-9","status":"publish","type":"class","link":"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/","title":{"rendered":"Ananda Dansa: \u00ab\u00c2tman, el comiat\u00bb"},"content":{"rendered":"<h2>Les arts \u00e9s dansa &#8211; \u00c2tman, el comiat<\/h2>\n<p>Valencia &#8211; Palau de Les Arts Reina Sofia<br \/>Avenida del Profesor Lopez Pi\u00f1ero, 1<br \/>31\/01\/2020<br \/>20:00<\/p>\n<p>La compa\u00f1\u00eda <em>Ananda Dansa<\/em>, una de las m\u00e1s importantes de Espa\u00f1a en el repertorio de danza contempor\u00e1nea, presenta su \u00faltimo espect\u00e1culo \u00ab\u00c2tman, el comiat\u00bb, una reflexi\u00f3n art\u00edstica, compasiva y po\u00e9tica sobre ese amor que genera violencia, que desgarra hasta incluso la vida de aquellos a quienes amas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les arts \u00e9s dansa &#8211; \u00c2tman, el comiat Valencia &#8211; Palau de Les Arts Reina SofiaAvenida del Profesor Lopez Pi\u00f1ero, 131\/01\/202020:00 La compa\u00f1\u00eda Ananda Dansa, una de las m\u00e1s importantes de Espa\u00f1a en el repertorio de danza contempor\u00e1nea, presenta su \u00faltimo espect\u00e1culo \u00ab\u00c2tman, el comiat\u00bb, una reflexi\u00f3n art\u00edstica, compasiva y po\u00e9tica sobre ese amor que genera violencia, que desgarra hasta incluso la vida de aquellos a quienes amas.<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[5085,5046],"wcs-room":[5447],"wcs-instructor":[],"class_list":["post-39377","class","type-class","status-publish","hentry","wcs-type-baile","wcs-type-musica","wcs-room-valencia-palau-de-les-arts-reina-sofia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ananda Dansa: &quot;\u00c2tman, el comiat&quot; - COSTA BLANCA UP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ananda Dansa: &quot;\u00c2tman, el comiat&quot; - COSTA BLANCA UP\" \/>\n<meta property=\"og:description\" content=\"Les arts \u00e9s dansa &#8211; \u00c2tman, el comiat Valencia &#8211; Palau de Les Arts Reina SofiaAvenida del Profesor Lopez Pi\u00f1ero, 131\/01\/202020:00 La compa\u00f1\u00eda Ananda Dansa, una de las m\u00e1s importantes de Espa\u00f1a en el repertorio de danza contempor\u00e1nea, presenta su \u00faltimo espect\u00e1culo \u00ab\u00c2tman, el comiat\u00bb, una reflexi\u00f3n art\u00edstica, compasiva y po\u00e9tica sobre ese amor que genera violencia, que desgarra hasta incluso la vida de aquellos a quienes amas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/ananda-dansa-atman-el-comiat-9\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/ananda-dansa-atman-el-comiat-9\\\/\",\"name\":\"Ananda Dansa: \\\"\u00c2tman, el comiat\\\" - COSTA BLANCA UP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"datePublished\":\"2020-01-15T08:47:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/ananda-dansa-atman-el-comiat-9\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/ananda-dansa-atman-el-comiat-9\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/ananda-dansa-atman-el-comiat-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ananda Dansa: \u00ab\u00c2tman, el comiat\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ananda Dansa: \"\u00c2tman, el comiat\" - COSTA BLANCA UP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/","og_locale":"es_ES","og_type":"article","og_title":"Ananda Dansa: \"\u00c2tman, el comiat\" - COSTA BLANCA UP","og_description":"Les arts \u00e9s dansa &#8211; \u00c2tman, el comiat Valencia &#8211; Palau de Les Arts Reina SofiaAvenida del Profesor Lopez Pi\u00f1ero, 131\/01\/202020:00 La compa\u00f1\u00eda Ananda Dansa, una de las m\u00e1s importantes de Espa\u00f1a en el repertorio de danza contempor\u00e1nea, presenta su \u00faltimo espect\u00e1culo \u00ab\u00c2tman, el comiat\u00bb, una reflexi\u00f3n art\u00edstica, compasiva y po\u00e9tica sobre ese amor que genera violencia, que desgarra hasta incluso la vida de aquellos a quienes amas.","og_url":"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/","og_site_name":"COSTA BLANCA UP","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/","url":"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/","name":"Ananda Dansa: \"\u00c2tman, el comiat\" - COSTA BLANCA UP","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"datePublished":"2020-01-15T08:47:22+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/class\/ananda-dansa-atman-el-comiat-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ananda Dansa: \u00ab\u00c2tman, el comiat\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class\/39377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=39377"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-type?post=39377"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-room?post=39377"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-instructor?post=39377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}