{"id":47692,"date":"2021-01-08T10:15:13","date_gmt":"2021-01-08T09:15:13","guid":{"rendered":"https:\/\/costablancaup.com\/class\/mundomar-benidorm-2021-9-2\/"},"modified":"2021-05-18T17:59:53","modified_gmt":"2021-05-18T15:59:53","slug":"terra-natura-benidorm-2021-10","status":"publish","type":"class","link":"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/","title":{"rendered":"Terra Natura Benidorm"},"content":{"rendered":"<h2>Terra Natura Benidorm es un parque zool\u00f3gico de nueva generaci\u00f3n ubicado en Benidorm (Alicante).<\/h2>\n<p>Ha sido dise\u00f1ado bajo el concepto de <em>zooinmersi\u00f3n<\/em>, un nuevo concepto en el dise\u00f1o de h\u00e1bitats que pemite a los visitantes observar a los animales a trav\u00e9s de barreras invisibles a los ojos del ser humano garantizando su seguridad.<\/p>\n<p>El parque ocupa una superficie pr\u00f3xima a los 320.000 metros cuadrados, y en sus instalaciones viven m\u00e1s de 1500 animales de 200 especies diferentes, divididos en cuatro zonas: Europa, Pangea, Am\u00e9rica y Asia.<\/p>\n<p>Entre las especies destacan: rapaces (halcones, \u00e1guilas, buhos, &#8230;), ex\u00f3ticas aves (flamencos, tucanes, guacamayos, &#8230;), criaturas venenosas (tar\u00e1ntulas, escorpiones, reptiles,&#8230;) y mam\u00edferos (monos, llamas, jaguares, ocelotes, tigres, leones, rinocerontes, elefantes, &#8230;).<\/p>\n<p><em>Terra Natura Benidorm<\/em> no es s\u00f3lo un parque de animales, el recorrido de estos parques muestra adem\u00e1s de los distintos ejemplares, curiosas caracter\u00edsticas de su h\u00e1bitat, vegetaci\u00f3n y peculiaridades de cada especie.<\/p>\n<p>Sus distintas propuestas educativas y actividades al aire libre, lo convierte en un lugar id\u00edlico para disfrutar de la naturaleza en familia y que los m\u00e1s peque\u00f1os aprendan y se diviertan.<\/p>\n<p>El parque dispone de muchos servicios como <em>parking<\/em> de pago, consignas, vestuarios, tiendas de regalos, zona de <em>picnic<\/em>, kioskos, restaurantes y de un espacio multiaventura con puentes colgantes, tirolinas, columpios y toneles.<\/p>\n<p><strong>Abierto m\u00e1s de 300 d\u00edas al a\u00f1o, desde el 2 de enero hasta el 31 de diciembre de 2021, con diferentes horarios de apertura y cierre dependiendo de la \u00e9poca.<\/strong><\/p>\n<p class=\"tickets\"><a target=\"_blank\" title=\"Ampliar informaci\u00f3n y reservar\" href=\"https:\/\/www.taquilla.com\/entradas\/terra-natura-benidorm?t10id=1088\" rel=\"noopener noreferrer\">Ampliar informaci\u00f3n y reservar<\/a><\/p>\n<h3>Localizaci\u00f3n<\/h3>\n\r\n            \r\n            \r\n            \r\n            <a name='map23'><\/a>\r\n            \r\n            \r\n            \r\n            \r\n            <div class=\"wpgmza_map \"  id=\"wpgmza_map_23\" style=\"display:block; overflow:auto; width:100%; height:400px; float:left;\" data-settings='{\"id\":\"23\",\"map_title\":\"Terra Natura Benidorm\",\"map_width\":\"100\",\"map_height\":\"400\",\"map_start_lat\":\"38.563932\",\"map_start_lng\":\"-0.117561\",\"map_start_location\":\"38.56393195075119,-0.11756074322512022\",\"map_start_zoom\":\"13\",\"default_marker\":\"0\",\"type\":\"1\",\"alignment\":\"1\",\"directions_enabled\":\"0\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"1\",\"dbox_width\":\"100\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"\\\\%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"0\",\"ugm_access\":\"0\",\"order_markers_by\":\"1\",\"order_markers_choice\":\"2\",\"show_user_location\":\"2\",\"default_to\":\"\",\"other_settings\":{\"wpgmza_store_locator_restrict\":\"\",\"wpgmza_sl_animation\":\"1\",\"store_locator_query_string\":\"ZIP \\\/ Address:\",\"store_locator_name_string\":\"Title \\\/ Description:\",\"store_locator_default_address\":\"\",\"wpgmza_dbox_width_type\":\"%\",\"map_max_zoom\":\"3\",\"map_min_zoom\":\"21\",\"sl_stroke_color\":\"FF0000\",\"sl_stroke_opacity\":\"0.25\",\"sl_fill_color\":\"FF0000\",\"sl_fill_opacity\":\"0.15\",\"click_open_link\":2,\"transport_layer\":0,\"iw_primary_color\":\"2A3744\",\"iw_accent_color\":\"252F3A\",\"iw_text_color\":\"FFFFFF\",\"wpgmza_iw_type\":\"0\",\"list_markers_by\":\"0\",\"push_in_map\":\"\",\"push_in_map_placement\":\"9\",\"wpgmza_push_in_map_width\":\"\",\"wpgmza_push_in_map_height\":\"\",\"wpgmza_theme_data\":\"\",\"upload_default_ul_marker\":\"\",\"upload_default_sl_marker\":\"\",\"shortcodeAttributes\":{\"id\":\"23\"}}}' data-map-id='23' data-shortcode-attributes='{\"id\":\"23\"}'> <\/div>\r\n            \r\n               \r\n        \n","protected":false},"excerpt":{"rendered":"<p>Terra Natura Benidorm es un parque zool\u00f3gico de nueva generaci\u00f3n ubicado en Benidorm (Alicante). Ha sido dise\u00f1ado bajo el concepto de zooinmersi\u00f3n, un nuevo concepto en el dise\u00f1o de h\u00e1bitats que pemite a los visitantes observar a los animales a trav\u00e9s de barreras invisibles a los ojos del ser humano garantizando su seguridad. El parque ocupa una superficie pr\u00f3xima a los 320.000 metros cuadrados, y en sus instalaciones viven m\u00e1s de 1500 animales de 200 especies diferentes, divididos en cuatro zonas: Europa, Pangea, Am\u00e9rica y Asia. Entre las especies destacan: rapaces (halcones, \u00e1guilas, buhos, &#8230;), ex\u00f3ticas aves (flamencos, tucanes, guacamayos, [&hellip;]<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[5036,5224],"wcs-room":[5240],"wcs-instructor":[],"class_list":["post-47692","class","type-class","status-publish","hentry","wcs-type-ninos","wcs-type-turismo","wcs-room-terra-natura-benidorm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terra Natura Benidorm - COSTA BLANCA UP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terra Natura Benidorm - COSTA BLANCA UP\" \/>\n<meta property=\"og:description\" content=\"Terra Natura Benidorm es un parque zool\u00f3gico de nueva generaci\u00f3n ubicado en Benidorm (Alicante). Ha sido dise\u00f1ado bajo el concepto de zooinmersi\u00f3n, un nuevo concepto en el dise\u00f1o de h\u00e1bitats que pemite a los visitantes observar a los animales a trav\u00e9s de barreras invisibles a los ojos del ser humano garantizando su seguridad. El parque ocupa una superficie pr\u00f3xima a los 320.000 metros cuadrados, y en sus instalaciones viven m\u00e1s de 1500 animales de 200 especies diferentes, divididos en cuatro zonas: Europa, Pangea, Am\u00e9rica y Asia. Entre las especies destacan: rapaces (halcones, \u00e1guilas, buhos, &#8230;), ex\u00f3ticas aves (flamencos, tucanes, guacamayos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-18T15:59:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/terra-natura-benidorm-2021-10\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/terra-natura-benidorm-2021-10\\\/\",\"name\":\"Terra Natura Benidorm - COSTA BLANCA UP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"datePublished\":\"2021-01-08T09:15:13+00:00\",\"dateModified\":\"2021-05-18T15:59:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/terra-natura-benidorm-2021-10\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/terra-natura-benidorm-2021-10\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/terra-natura-benidorm-2021-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terra Natura Benidorm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terra Natura Benidorm - COSTA BLANCA UP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/","og_locale":"es_ES","og_type":"article","og_title":"Terra Natura Benidorm - COSTA BLANCA UP","og_description":"Terra Natura Benidorm es un parque zool\u00f3gico de nueva generaci\u00f3n ubicado en Benidorm (Alicante). Ha sido dise\u00f1ado bajo el concepto de zooinmersi\u00f3n, un nuevo concepto en el dise\u00f1o de h\u00e1bitats que pemite a los visitantes observar a los animales a trav\u00e9s de barreras invisibles a los ojos del ser humano garantizando su seguridad. El parque ocupa una superficie pr\u00f3xima a los 320.000 metros cuadrados, y en sus instalaciones viven m\u00e1s de 1500 animales de 200 especies diferentes, divididos en cuatro zonas: Europa, Pangea, Am\u00e9rica y Asia. Entre las especies destacan: rapaces (halcones, \u00e1guilas, buhos, &#8230;), ex\u00f3ticas aves (flamencos, tucanes, guacamayos, [&hellip;]","og_url":"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/","og_site_name":"COSTA BLANCA UP","article_modified_time":"2021-05-18T15:59:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/","url":"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/","name":"Terra Natura Benidorm - COSTA BLANCA UP","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"datePublished":"2021-01-08T09:15:13+00:00","dateModified":"2021-05-18T15:59:53+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/class\/terra-natura-benidorm-2021-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Terra Natura Benidorm"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class\/47692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=47692"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-type?post=47692"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-room?post=47692"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-instructor?post=47692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}