{"id":50994,"date":"2022-01-17T19:45:43","date_gmt":"2022-01-17T18:45:43","guid":{"rendered":"https:\/\/costablancaup.com\/?post_type=class&#038;p=50994"},"modified":"2022-01-17T19:45:44","modified_gmt":"2022-01-17T18:45:44","slug":"el-jose-concierto-alicante","status":"publish","type":"class","link":"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/","title":{"rendered":"El Jose: \u00abConcierto\u00bb (Alicante)"},"content":{"rendered":"<h2>El Jose en Alicante<\/h2>\n<p>Alicante &#8211; Sala Stereo<br \/>\nC \/ Pintor Velazquez, 5. Alicante<br \/>\n07\/05\/2022<br \/>\n22:30<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Jose en Alicante Alicante &#8211; Sala Stereo C \/ Pintor Velazquez, 5. Alicante 07\/05\/2022 22:30<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[5168,5046],"wcs-room":[5464],"wcs-instructor":[],"class_list":["post-50994","class","type-class","status-publish","hentry","wcs-type-music","wcs-type-musica","wcs-room-alicante-sala-stereo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Jose: &quot;Concierto&quot; (Alicante) - COSTA BLANCA UP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Jose: &quot;Concierto&quot; (Alicante) - COSTA BLANCA UP\" \/>\n<meta property=\"og:description\" content=\"El Jose en Alicante Alicante &#8211; Sala Stereo C \/ Pintor Velazquez, 5. Alicante 07\/05\/2022 22:30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-17T18:45:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/el-jose-concierto-alicante\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/el-jose-concierto-alicante\\\/\",\"name\":\"El Jose: \\\"Concierto\\\" (Alicante) - COSTA BLANCA UP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"datePublished\":\"2022-01-17T18:45:43+00:00\",\"dateModified\":\"2022-01-17T18:45:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/el-jose-concierto-alicante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/el-jose-concierto-alicante\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/class\\\/el-jose-concierto-alicante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Jose: &#8220;Concierto&#8221; (Alicante)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Jose: \"Concierto\" (Alicante) - COSTA BLANCA UP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/","og_locale":"es_ES","og_type":"article","og_title":"El Jose: \"Concierto\" (Alicante) - COSTA BLANCA UP","og_description":"El Jose en Alicante Alicante &#8211; Sala Stereo C \/ Pintor Velazquez, 5. Alicante 07\/05\/2022 22:30","og_url":"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/","og_site_name":"COSTA BLANCA UP","article_modified_time":"2022-01-17T18:45:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/","url":"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/","name":"El Jose: \"Concierto\" (Alicante) - COSTA BLANCA UP","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"datePublished":"2022-01-17T18:45:43+00:00","dateModified":"2022-01-17T18:45:44+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/class\/el-jose-concierto-alicante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Jose: &#8220;Concierto&#8221; (Alicante)"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class\/50994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=50994"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-type?post=50994"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-room?post=50994"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/wcs-instructor?post=50994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}