{"id":22988,"date":"2018-12-18T15:25:09","date_gmt":"2018-12-18T14:25:09","guid":{"rendered":"https:\/\/costablancaup.com\/?p=22988"},"modified":"2018-12-20T16:30:02","modified_gmt":"2018-12-20T15:30:02","slug":"conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante","status":"publish","type":"post","link":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/","title":{"rendered":"Conoce los mejores mercadillos y ferias de Navidad de Alicante"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg\" alt=\"Mercadillos de Navidad de Alicante\" width=\"800\" height=\"446\" class=\"aligncenter size-full wp-image-22989\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante-300x167.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante-768x428.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante-400x223.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><br \/>\n<\/p>\n<div class=\"piefoto\">Por pixabay.com<\/div>\n<p><\/p>\n<h2>Disfruta de estas fiestas recorriendo los puestos de los mercados navide\u00f1os de Alicante.<\/h2>\n<p>En los puestos y talleres artesanos podr\u00e1 encontrar desde productos y decoraci\u00f3n propia de estas fechas hasta originales regalos con los que sorprender\u00e1 a grandes y peque\u00f1os.<\/p>\n<p>Estos son algunos de los mercados que puede visitar en Alicante ciudad y provincia:<\/p>\n<h3>Programa<\/h3>\n<p style=\"margin-bottom: 0;\">\n<strong>Mercadillo de Artesan\u00eda de Navidad<\/strong><br \/>\nLugar: Paseo Federico Soto de Alicante<br \/>\nFechas: Hasta el 5 de enero.<br \/>\nHorario: <\/p>\n<ul>\n<li>De 10:00 a 15:00 y de 17:00 a 23:00 horas.<\/li>\n<li>El 5 de enero, de 10:00 a 15:00 y de 17:00 a 00:00 horas.<\/li>\n<\/ul>\n<p style=\"margin-bottom: 0;\">\n<strong>Christmas Market Seneca<\/strong><br \/>\nLugar: Hall del Edificio S\u00e9neca. Plaza S\u00e9neca de Alicante<br \/>\nFechas: Hasta el 23 de diciembre.<br \/>\nHorario: <\/p>\n<ul>\n<li>De 11:00 a 21:00 horas.<\/li>\n<li>El 22 y 23 de diciembre, de 11:00 a 22:00 horas.<\/li>\n<\/ul>\n<p style=\"margin-bottom: 0;\">\n<strong>Mercado Artesano Navide\u00f1o<\/strong><br \/>\nLugar: Palacio de la Diputaci\u00f3n de Alicante<br \/>\nFechas: Hasta el 6 de enero.<br \/>\nHorario: <\/p>\n<ul>\n<li>De 11:00 a 23:00 horas.<\/li>\n<li>S\u00e1bados y v\u00edsperas de festivo, de 11:00 a 23:30 horas.<\/li>\n<\/ul>\n<p style=\"margin-bottom: 0;\">\n<strong>Mercado Navide\u00f1o \u00abLa Paca Vintage\u00bb<\/strong><br \/>\nLugar: Paseo Campoamor de Alicante<br \/>\nFechas: Del 21 al 23 de diciembre.<br \/>\nHorario: <\/p>\n<ul>\n<li>De 11:00 a 22:00 horas.<\/li>\n<\/ul>\n<p style=\"margin-bottom: 0;\">\n<strong>Mercadito de la Cascaruja<\/strong><br \/>\nLugar: Paseo Federico Soto de Alicante<br \/>\nFechas: Hasta el 24 de diciembre.<br \/>\nHorario: <\/p>\n<ul>\n<li>De 10:00 a 15:00 y 17:00 a 23:00 horas.<\/li>\n<\/ul>\n<p style=\"margin-bottom: 0;\">\n<strong>Mercadillo de Navidad en Elche<\/strong><br \/>\nLugar: Glorieta de Elche<br \/>\nFechas: Hasta el 5 de enero.<br \/>\nHorario: <\/p>\n<ul>\n<li>Viernes y s\u00e1bados, de 11:00 a 14:00 y 18:00 a 22:00 horas.<\/li>\n<\/ul>\n<p style=\"margin-bottom: 0;\">\n<strong>Mercado navide\u00f1o en Orihuela<\/strong><br \/>\nLugar: Glorieta Gabriel Mir\u00f3 de Orihuela<br \/>\nFechas: Hasta el 24 de diciembre.<br \/>\nHorario: <\/p>\n<ul>\n<li>De 10:00 a 14:00 y 17:00 a 21:00 horas.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Disfruta de estas fiestas recorriendo los puestos de los mercados navide\u00f1os de Alicante. En los puestos y talleres artesanos podr\u00e1 encontrar desde productos y decoraci\u00f3n propia de estas fechas hasta originales regalos con los que sorprender\u00e1 a grandes y peque\u00f1os. Estos son algunos de los mercados que puede visitar en Alicante ciudad y provincia: Programa Mercadillo de Artesan\u00eda de Navidad Lugar: Paseo Federico Soto de Alicante Fechas: Hasta el 5 de enero. Horario: De 10:00 a 15:00 y de 17:00 a 23:00 horas. El 5 de enero, de 10:00 a 15:00 y de 17:00 a 00:00 horas. Christmas Market Seneca [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22989,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5015],"tags":[5070],"class_list":["post-22988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-culturales","tag-alicante-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSTA BLANCA UP - Conoce los mejores mercadillos y ferias de Navidad de Alicante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSTA BLANCA UP - Conoce los mejores mercadillos y ferias de Navidad de Alicante\" \/>\n<meta property=\"og:description\" content=\"Disfruta de estas fiestas recorriendo los puestos de los mercados navide\u00f1os de Alicante. En los puestos y talleres artesanos podr\u00e1 encontrar desde productos y decoraci\u00f3n propia de estas fechas hasta originales regalos con los que sorprender\u00e1 a grandes y peque\u00f1os. Estos son algunos de los mercados que puede visitar en Alicante ciudad y provincia: Programa Mercadillo de Artesan\u00eda de Navidad Lugar: Paseo Federico Soto de Alicante Fechas: Hasta el 5 de enero. Horario: De 10:00 a 15:00 y de 17:00 a 23:00 horas. El 5 de enero, de 10:00 a 15:00 y de 17:00 a 00:00 horas. Christmas Market Seneca [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-18T14:25:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-20T15:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/\"},\"author\":{\"name\":\"jas_admin\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\"},\"headline\":\"Conoce los mejores mercadillos y ferias de Navidad de Alicante\",\"datePublished\":\"2018-12-18T14:25:09+00:00\",\"dateModified\":\"2018-12-20T15:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/mercado-navidad-alicante.jpg\",\"keywords\":[\"Alicante\"],\"articleSection\":[\"Eventos culturales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/\",\"name\":\"COSTA BLANCA UP - Conoce los mejores mercadillos y ferias de Navidad de Alicante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/mercado-navidad-alicante.jpg\",\"datePublished\":\"2018-12-18T14:25:09+00:00\",\"dateModified\":\"2018-12-20T15:30:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/mercado-navidad-alicante.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/mercado-navidad-alicante.jpg\",\"width\":800,\"height\":446,\"caption\":\"Mercadillos de Navidad de Alicante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conoce los mejores mercadillos y ferias de Navidad de Alicante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\",\"name\":\"jas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"caption\":\"jas_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSTA BLANCA UP - Conoce los mejores mercadillos y ferias de Navidad de Alicante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/","og_locale":"es_ES","og_type":"article","og_title":"COSTA BLANCA UP - Conoce los mejores mercadillos y ferias de Navidad de Alicante","og_description":"Disfruta de estas fiestas recorriendo los puestos de los mercados navide\u00f1os de Alicante. En los puestos y talleres artesanos podr\u00e1 encontrar desde productos y decoraci\u00f3n propia de estas fechas hasta originales regalos con los que sorprender\u00e1 a grandes y peque\u00f1os. Estos son algunos de los mercados que puede visitar en Alicante ciudad y provincia: Programa Mercadillo de Artesan\u00eda de Navidad Lugar: Paseo Federico Soto de Alicante Fechas: Hasta el 5 de enero. Horario: De 10:00 a 15:00 y de 17:00 a 23:00 horas. El 5 de enero, de 10:00 a 15:00 y de 17:00 a 00:00 horas. Christmas Market Seneca [&hellip;]","og_url":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/","og_site_name":"COSTA BLANCA UP","article_published_time":"2018-12-18T14:25:09+00:00","article_modified_time":"2018-12-20T15:30:02+00:00","og_image":[{"width":800,"height":446,"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg","type":"image\/jpeg"}],"author":"jas_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jas_admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#article","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/"},"author":{"name":"jas_admin","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489"},"headline":"Conoce los mejores mercadillos y ferias de Navidad de Alicante","datePublished":"2018-12-18T14:25:09+00:00","dateModified":"2018-12-20T15:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"image":{"@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg","keywords":["Alicante"],"articleSection":["Eventos culturales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/","url":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/","name":"COSTA BLANCA UP - Conoce los mejores mercadillos y ferias de Navidad de Alicante","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg","datePublished":"2018-12-18T14:25:09+00:00","dateModified":"2018-12-20T15:30:02+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/mercado-navidad-alicante.jpg","width":800,"height":446,"caption":"Mercadillos de Navidad de Alicante"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/conoce-los-mejores-mercadillos-y-ferias-de-navidad-de-alicante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Conoce los mejores mercadillos y ferias de Navidad de Alicante"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489","name":"jas_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","caption":"jas_admin"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/22988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/comments?post=22988"}],"version-history":[{"count":3,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/22988\/revisions"}],"predecessor-version":[{"id":23013,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/22988\/revisions\/23013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media\/22989"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=22988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/categories?post=22988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/tags?post=22988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}