{"id":23149,"date":"2018-12-26T12:22:52","date_gmt":"2018-12-26T11:22:52","guid":{"rendered":"https:\/\/costablancaup.com\/?p=23149"},"modified":"2018-12-26T12:23:28","modified_gmt":"2018-12-26T11:23:28","slug":"no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi","status":"publish","type":"post","link":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/","title":{"rendered":"No te pierdas el 28 de diciembre la singular \u00abFesta del Enfarinats\u00bb en Ibi"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg\" alt=\"Festa dels Enfarinats\" width=\"1024\" height=\"608\" class=\"aligncenter size-full wp-image-23150\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg 1024w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi-300x178.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi-768x456.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi-400x238.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br \/>\n<\/p>\n<div class=\"piefoto\">Por wikipedia.org<\/div>\n<p><\/p>\n<h2>En la fiesta, con m\u00e1s de 200 a\u00f1os de antig\u00fcedad, un grupo de insurgentes ataviados con vestimentas estrafalarias y con el rostro completamente embadurnado de harina (\u00abels enfarinats\u00bb), se adue\u00f1an simb\u00f3licamente de la ciudad de Ibi y la someten a su caprichosa voluntad.<\/h2>\n<p>Una vez tomado el poder, \u00abel enfarinats\u00bb recaudan fondos en los comercios (dinero que se destina a causas ben\u00e9ficas) e imponen en el pueblo la dictadura de lo absurdo: \u00abDurante todo el d\u00eda no se puede caminar por la acera o por la calzada, ni tampoco por el sol, ni por la sombra\u00bb.<\/p>\n<p>Miles de kilos de harina y polvos de talco, cientos de docenas de huevos, y centenares de cohetes y petardos ser\u00e1n la munici\u00f3n con la que \u00abel enfarinats\u00bb se enfrenter\u00e1n a sus opositores en un ambiente carnavelesco y burl\u00f3n.<\/p>\n<p>El p\u00fablico asistente puede presenciar la fiesta desde la parte alta de la plaza de la Iglesia y llevarse un recuerdo increible de una de las tradiciones m\u00e1s emblem\u00e1ticas de Ibi.<\/p>\n<h3>Horarios<\/h3>\n<ul>\n<li>Inicio de la fiesta, a las 8:00 horas.<\/li>\n<li>Carrera para decidir qui\u00e9n es el nuevo alcalde, en la calle de Les Eres, a las 9:00 horas.<\/li>\n<li>Fin de la batalla y la fiesta, a las 12:00 horas.<\/li>\n<\/ul>\n<h3>Localizaci\u00f3n<\/h3>\n\r\n            \r\n            \r\n            \r\n            <a name='map104'><\/a>\r\n            \r\n            \r\n            \r\n            \r\n            <div class=\"wpgmza_map \"  id=\"wpgmza_map_104\" style=\"display:block; overflow:auto; width:100%; height:400px; float:left;\" data-settings='{\"id\":\"104\",\"map_title\":\"Plaza de La Iglesia (Ibi)\",\"map_width\":\"100\",\"map_height\":\"400\",\"map_start_lat\":\"38.624910\",\"map_start_lng\":\"-0.575900\",\"map_start_location\":\"38.624910122895095,-0.575900239124516\",\"map_start_zoom\":\"15\",\"default_marker\":\"0\",\"type\":\"1\",\"alignment\":\"1\",\"directions_enabled\":\"0\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"1\",\"dbox_width\":\"100\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"\\\\%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"0\",\"ugm_access\":\"0\",\"order_markers_by\":\"1\",\"order_markers_choice\":\"2\",\"show_user_location\":\"2\",\"default_to\":\"\",\"other_settings\":{\"wpgmza_store_locator_restrict\":\"\",\"wpgmza_sl_animation\":\"1\",\"store_locator_query_string\":\"ZIP \\\/ Address:\",\"store_locator_name_string\":\"Title \\\/ Description:\",\"store_locator_default_address\":\"\",\"wpgmza_dbox_width_type\":\"%\",\"map_max_zoom\":\"3\",\"map_min_zoom\":\"21\",\"sl_stroke_color\":\"FF0000\",\"sl_stroke_opacity\":\"0.25\",\"sl_fill_color\":\"FF0000\",\"sl_fill_opacity\":\"0.15\",\"click_open_link\":2,\"transport_layer\":0,\"iw_primary_color\":\"2A3744\",\"iw_accent_color\":\"252F3A\",\"iw_text_color\":\"FFFFFF\",\"wpgmza_iw_type\":\"0\",\"list_markers_by\":\"0\",\"push_in_map\":\"\",\"push_in_map_placement\":\"9\",\"wpgmza_push_in_map_width\":\"\",\"wpgmza_push_in_map_height\":\"\",\"wpgmza_theme_data\":\"\",\"upload_default_ul_marker\":\"\",\"upload_default_sl_marker\":\"\",\"shortcodeAttributes\":{\"id\":\"104\"}}}' data-map-id='104' data-shortcode-attributes='{\"id\":\"104\"}'> <\/div>\r\n            \r\n               \r\n        \n","protected":false},"excerpt":{"rendered":"<p>En la fiesta, con m\u00e1s de 200 a\u00f1os de antig\u00fcedad, un grupo de insurgentes ataviados con vestimentas estrafalarias y con el rostro completamente embadurnado de harina (\u00abels enfarinats\u00bb), se adue\u00f1an simb\u00f3licamente de la ciudad de Ibi y la someten a su caprichosa voluntad. Una vez tomado el poder, \u00abel enfarinats\u00bb recaudan fondos en los comercios (dinero que se destina a causas ben\u00e9ficas) e imponen en el pueblo la dictadura de lo absurdo: \u00abDurante todo el d\u00eda no se puede caminar por la acera o por la calzada, ni tampoco por el sol, ni por la sombra\u00bb. Miles de kilos de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23150,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5016],"tags":[5374],"class_list":["post-23149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas-eventos","tag-ibi-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSTA BLANCA UP - No te pierdas el 28 de diciembre la singular &quot;Festa del Enfarinats&quot; en Ibi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSTA BLANCA UP - No te pierdas el 28 de diciembre la singular &quot;Festa del Enfarinats&quot; en Ibi\" \/>\n<meta property=\"og:description\" content=\"En la fiesta, con m\u00e1s de 200 a\u00f1os de antig\u00fcedad, un grupo de insurgentes ataviados con vestimentas estrafalarias y con el rostro completamente embadurnado de harina (\u00abels enfarinats\u00bb), se adue\u00f1an simb\u00f3licamente de la ciudad de Ibi y la someten a su caprichosa voluntad. Una vez tomado el poder, \u00abel enfarinats\u00bb recaudan fondos en los comercios (dinero que se destina a causas ben\u00e9ficas) e imponen en el pueblo la dictadura de lo absurdo: \u00abDurante todo el d\u00eda no se puede caminar por la acera o por la calzada, ni tampoco por el sol, ni por la sombra\u00bb. Miles de kilos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-26T11:22:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-26T11:23:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/\"},\"author\":{\"name\":\"jas_admin\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\"},\"headline\":\"No te pierdas el 28 de diciembre la singular \u00abFesta del Enfarinats\u00bb en Ibi\",\"datePublished\":\"2018-12-26T11:22:52+00:00\",\"dateModified\":\"2018-12-26T11:23:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/\"},\"wordCount\":237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/enfarinats-ibi.jpg\",\"keywords\":[\"Ibi\"],\"articleSection\":[\"Fiestas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/\",\"name\":\"COSTA BLANCA UP - No te pierdas el 28 de diciembre la singular \\\"Festa del Enfarinats\\\" en Ibi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/enfarinats-ibi.jpg\",\"datePublished\":\"2018-12-26T11:22:52+00:00\",\"dateModified\":\"2018-12-26T11:23:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/enfarinats-ibi.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/enfarinats-ibi.jpg\",\"width\":1024,\"height\":608,\"caption\":\"Festa dels Enfarinats\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No te pierdas el 28 de diciembre la singular \u00abFesta del Enfarinats\u00bb en Ibi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\",\"name\":\"jas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"caption\":\"jas_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSTA BLANCA UP - No te pierdas el 28 de diciembre la singular \"Festa del Enfarinats\" en Ibi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/","og_locale":"es_ES","og_type":"article","og_title":"COSTA BLANCA UP - No te pierdas el 28 de diciembre la singular \"Festa del Enfarinats\" en Ibi","og_description":"En la fiesta, con m\u00e1s de 200 a\u00f1os de antig\u00fcedad, un grupo de insurgentes ataviados con vestimentas estrafalarias y con el rostro completamente embadurnado de harina (\u00abels enfarinats\u00bb), se adue\u00f1an simb\u00f3licamente de la ciudad de Ibi y la someten a su caprichosa voluntad. Una vez tomado el poder, \u00abel enfarinats\u00bb recaudan fondos en los comercios (dinero que se destina a causas ben\u00e9ficas) e imponen en el pueblo la dictadura de lo absurdo: \u00abDurante todo el d\u00eda no se puede caminar por la acera o por la calzada, ni tampoco por el sol, ni por la sombra\u00bb. Miles de kilos de [&hellip;]","og_url":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/","og_site_name":"COSTA BLANCA UP","article_published_time":"2018-12-26T11:22:52+00:00","article_modified_time":"2018-12-26T11:23:28+00:00","og_image":[{"width":1024,"height":608,"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg","type":"image\/jpeg"}],"author":"jas_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jas_admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#article","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/"},"author":{"name":"jas_admin","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489"},"headline":"No te pierdas el 28 de diciembre la singular \u00abFesta del Enfarinats\u00bb en Ibi","datePublished":"2018-12-26T11:22:52+00:00","dateModified":"2018-12-26T11:23:28+00:00","mainEntityOfPage":{"@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/"},"wordCount":237,"commentCount":0,"publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"image":{"@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg","keywords":["Ibi"],"articleSection":["Fiestas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/","url":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/","name":"COSTA BLANCA UP - No te pierdas el 28 de diciembre la singular \"Festa del Enfarinats\" en Ibi","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg","datePublished":"2018-12-26T11:22:52+00:00","dateModified":"2018-12-26T11:23:28+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/12\/enfarinats-ibi.jpg","width":1024,"height":608,"caption":"Festa dels Enfarinats"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/no-te-pierdas-el-28-de-diciembre-la-singular-festa-del-enfarinats-en-ibi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"No te pierdas el 28 de diciembre la singular \u00abFesta del Enfarinats\u00bb en Ibi"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489","name":"jas_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","caption":"jas_admin"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/23149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/comments?post=23149"}],"version-history":[{"count":1,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/23149\/revisions"}],"predecessor-version":[{"id":23155,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/23149\/revisions\/23155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media\/23150"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=23149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/categories?post=23149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/tags?post=23149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}