{"id":31523,"date":"2019-06-25T11:01:40","date_gmt":"2019-06-25T09:01:40","guid":{"rendered":"https:\/\/costablancaup.com\/?p=31523"},"modified":"2019-06-25T11:02:19","modified_gmt":"2019-06-25T09:02:19","slug":"concurso-de-fuegos-artificiales-de-hogueras-de-san-juan","status":"publish","type":"post","link":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/","title":{"rendered":"Concurso de \u00abFuegos artificiales de Hogueras de San Juan\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg\" alt=\"Hogueras de San Juan 2019\" width=\"1024\" height=\"576\" class=\"aligncenter size-full wp-image-31212\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg 1024w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019-300x169.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019-768x432.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019-400x225.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><br \/>\n<\/p>\n<div class=\"piefoto\">Por hogueras.com<\/div>\n<p><\/p>\n<h2>Del 25 al 29 de junio se disparar\u00e1n los castillos de fuegos artificiales a las 00:00 horas desde la <em>Playa del Coc\u00f3<\/em> de Alicante.<\/h2>\n<p>Durante las cinco noches siguientes a la \u00abcrem\u00e1\u00bb continuan las celebraciones de las \u00abHogueras\u00bb con este gran espect\u00e1culo de luz y sonido.<\/p>\n<p>Antes de medianoche la gente acude temprano para coger sitio en la playa del Postiguet y disfrutar de la mejor vista de los fuegos articiales. Cada castillo tiene una duraci\u00f3n de unos 15 minutos.<\/p>\n<h3>Localizaci\u00f3n<\/h3>\n\r\n            \r\n            \r\n            \r\n            <a name='map216'><\/a>\r\n            \r\n            \r\n            \r\n            \r\n            <div class=\"wpgmza_map \"  id=\"wpgmza_map_216\" style=\"display:block; overflow:auto; width:100%; height:400px; float:left;\" data-settings='{\"id\":\"216\",\"map_title\":\"Playa del Postiguet (Alicante)\",\"map_width\":\"100\",\"map_height\":\"400\",\"map_start_lat\":\"38.346200\",\"map_start_lng\":\"-0.483554\",\"map_start_location\":\"38.346199678617765,-0.48355428052458516\",\"map_start_zoom\":\"14\",\"default_marker\":\"0\",\"type\":\"1\",\"alignment\":\"1\",\"directions_enabled\":\"0\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"1\",\"dbox_width\":\"100\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"\\\\%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"0\",\"ugm_access\":\"0\",\"order_markers_by\":\"1\",\"order_markers_choice\":\"2\",\"show_user_location\":\"2\",\"default_to\":\"\",\"other_settings\":{\"wpgmza_store_locator_restrict\":\"\",\"wpgmza_sl_animation\":\"1\",\"store_locator_query_string\":\"ZIP \\\/ Address:\",\"store_locator_name_string\":\"Title \\\/ Description:\",\"store_locator_default_address\":\"\",\"wpgmza_dbox_width_type\":\"%\",\"map_max_zoom\":\"3\",\"map_min_zoom\":\"21\",\"sl_stroke_color\":\"FF0000\",\"sl_stroke_opacity\":\"0.25\",\"sl_fill_color\":\"FF0000\",\"sl_fill_opacity\":\"0.15\",\"click_open_link\":2,\"transport_layer\":0,\"iw_primary_color\":\"2A3744\",\"iw_accent_color\":\"252F3A\",\"iw_text_color\":\"FFFFFF\",\"wpgmza_iw_type\":\"0\",\"list_markers_by\":\"0\",\"push_in_map\":\"\",\"push_in_map_placement\":\"9\",\"wpgmza_push_in_map_width\":\"\",\"wpgmza_push_in_map_height\":\"\",\"wpgmza_theme_data\":\"\",\"upload_default_ul_marker\":\"\",\"upload_default_sl_marker\":\"\",\"shortcodeAttributes\":{\"id\":\"216\"}}}' data-map-id='216' data-shortcode-attributes='{\"id\":\"216\"}'> <\/div>\r\n            \r\n               \r\n        \n","protected":false},"excerpt":{"rendered":"<p>Del 25 al 29 de junio se disparar\u00e1n los castillos de fuegos artificiales a las 00:00 horas desde la Playa del Coc\u00f3 de Alicante. Durante las cinco noches siguientes a la \u00abcrem\u00e1\u00bb continuan las celebraciones de las \u00abHogueras\u00bb con este gran espect\u00e1culo de luz y sonido. Antes de medianoche la gente acude temprano para coger sitio en la playa del Postiguet y disfrutar de la mejor vista de los fuegos articiales. Cada castillo tiene una duraci\u00f3n de unos 15 minutos. Localizaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":31212,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5016],"tags":[5070],"class_list":["post-31523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas-eventos","tag-alicante-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSTA BLANCA UP - Concurso de &quot;Fuegos artificiales de Hogueras de San Juan&quot;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSTA BLANCA UP - Concurso de &quot;Fuegos artificiales de Hogueras de San Juan&quot;\" \/>\n<meta property=\"og:description\" content=\"Del 25 al 29 de junio se disparar\u00e1n los castillos de fuegos artificiales a las 00:00 horas desde la Playa del Coc\u00f3 de Alicante. Durante las cinco noches siguientes a la \u00abcrem\u00e1\u00bb continuan las celebraciones de las \u00abHogueras\u00bb con este gran espect\u00e1culo de luz y sonido. Antes de medianoche la gente acude temprano para coger sitio en la playa del Postiguet y disfrutar de la mejor vista de los fuegos articiales. Cada castillo tiene una duraci\u00f3n de unos 15 minutos. Localizaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-25T09:01:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-25T09:02:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jas_admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/\"},\"author\":{\"name\":\"jas_admin\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\"},\"headline\":\"Concurso de \u00abFuegos artificiales de Hogueras de San Juan\u00bb\",\"datePublished\":\"2019-06-25T09:01:40+00:00\",\"dateModified\":\"2019-06-25T09:02:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/\"},\"wordCount\":97,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hogueras-san-juan-alicante-2019.jpg\",\"keywords\":[\"Alicante\"],\"articleSection\":[\"Fiestas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/\",\"name\":\"COSTA BLANCA UP - Concurso de \\\"Fuegos artificiales de Hogueras de San Juan\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hogueras-san-juan-alicante-2019.jpg\",\"datePublished\":\"2019-06-25T09:01:40+00:00\",\"dateModified\":\"2019-06-25T09:02:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hogueras-san-juan-alicante-2019.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hogueras-san-juan-alicante-2019.jpg\",\"width\":1024,\"height\":576,\"caption\":\"Hogueras de San Juan 2019\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso de \u00abFuegos artificiales de Hogueras de San Juan\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\",\"name\":\"jas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"caption\":\"jas_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSTA BLANCA UP - Concurso de \"Fuegos artificiales de Hogueras de San Juan\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/","og_locale":"es_ES","og_type":"article","og_title":"COSTA BLANCA UP - Concurso de \"Fuegos artificiales de Hogueras de San Juan\"","og_description":"Del 25 al 29 de junio se disparar\u00e1n los castillos de fuegos artificiales a las 00:00 horas desde la Playa del Coc\u00f3 de Alicante. Durante las cinco noches siguientes a la \u00abcrem\u00e1\u00bb continuan las celebraciones de las \u00abHogueras\u00bb con este gran espect\u00e1culo de luz y sonido. Antes de medianoche la gente acude temprano para coger sitio en la playa del Postiguet y disfrutar de la mejor vista de los fuegos articiales. Cada castillo tiene una duraci\u00f3n de unos 15 minutos. Localizaci\u00f3n","og_url":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/","og_site_name":"COSTA BLANCA UP","article_published_time":"2019-06-25T09:01:40+00:00","article_modified_time":"2019-06-25T09:02:19+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg","type":"image\/jpeg"}],"author":"jas_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jas_admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#article","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/"},"author":{"name":"jas_admin","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489"},"headline":"Concurso de \u00abFuegos artificiales de Hogueras de San Juan\u00bb","datePublished":"2019-06-25T09:01:40+00:00","dateModified":"2019-06-25T09:02:19+00:00","mainEntityOfPage":{"@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/"},"wordCount":97,"commentCount":0,"publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"image":{"@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg","keywords":["Alicante"],"articleSection":["Fiestas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/","url":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/","name":"COSTA BLANCA UP - Concurso de \"Fuegos artificiales de Hogueras de San Juan\"","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg","datePublished":"2019-06-25T09:01:40+00:00","dateModified":"2019-06-25T09:02:19+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/06\/hogueras-san-juan-alicante-2019.jpg","width":1024,"height":576,"caption":"Hogueras de San Juan 2019"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/concurso-de-fuegos-artificiales-de-hogueras-de-san-juan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Concurso de \u00abFuegos artificiales de Hogueras de San Juan\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489","name":"jas_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","caption":"jas_admin"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/31523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/comments?post=31523"}],"version-history":[{"count":2,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/31523\/revisions"}],"predecessor-version":[{"id":31525,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/31523\/revisions\/31525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media\/31212"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=31523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/categories?post=31523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/tags?post=31523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}