{"id":37747,"date":"2019-11-27T09:04:13","date_gmt":"2019-11-27T08:04:13","guid":{"rendered":"https:\/\/costablancaup.com\/?p=37747"},"modified":"2021-06-03T11:44:28","modified_gmt":"2021-06-03T09:44:28","slug":"feria-de-coleccionistas-y-brocanters-de-jesus-pobre","status":"publish","type":"post","link":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/","title":{"rendered":"\u00abFeria de Coleccionistas y Brocanters\u00bb de Jes\u00fas Pobre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg\" alt=\"Feria de Coleccionistas y Brocanters de Jes\u00fas Pobre\" width=\"800\" height=\"434\" class=\"aligncenter size-full wp-image-37750\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre-300x163.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre-768x417.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre-400x217.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<\/p>\n<div class=\"piefoto\">Por brocantersjesuspobre.org<\/div>\n<p>\n<h2>El evento se celebra los primeros domingos de cada mes, de 9:00 a 14:00 horas, en el <em>Gran Riurau<\/em> de Jes\u00fas Pobre (Alicante).<\/h2>\n<p>En esta feria podr\u00e1 encontrar gran cantidad de objetos de coleccionismo y decoraci\u00f3n como muebles, espejos, relojes, piezas de cer\u00e1mica, cristal o porcelana, esculturas, bronces, l\u00e1mparas, monedas, objetos vintage, retro, industrial, antig\u00fcedades y un largo etc&#8230;<\/p>\n<p class=\"tickets\"><a target=\"_blank\" title=\"Ampliar informaci\u00f3n\" href=\"https:\/\/brocantersjesuspobre.org\/\" rel=\"noopener noreferrer\">Ampliar informaci\u00f3n<\/a><\/p>\n<h3>Localizaci\u00f3n<\/h3>\n\r\n            \r\n            \r\n            \r\n            <a name='map269'><\/a>\r\n            \r\n            \r\n            \r\n            \r\n            <div class=\"wpgmza_map \"  id=\"wpgmza_map_269\" style=\"display:block; overflow:auto; width:100%; height:400px; float:left;\" data-settings='{\"id\":\"269\",\"map_title\":\"Mercat del Riurau (Jes\\u00fas Pobre)\",\"map_width\":\"100\",\"map_height\":\"400\",\"map_start_lat\":\"38.798694\",\"map_start_lng\":\"0.085569\",\"map_start_location\":\"38.79869444864844,0.08556881463419153\",\"map_start_zoom\":\"17\",\"default_marker\":\"0\",\"type\":\"1\",\"alignment\":\"1\",\"directions_enabled\":\"0\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"1\",\"dbox_width\":\"100\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"\\\\%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"0\",\"ugm_access\":\"0\",\"order_markers_by\":\"1\",\"order_markers_choice\":\"2\",\"show_user_location\":\"2\",\"default_to\":\"\",\"other_settings\":{\"store_locator_style\":\"legacy\",\"wpgmza_store_locator_radius_style\":\"legacy\",\"directions_box_style\":\"modern\",\"wpgmza_dbox_width_type\":\"%\",\"map_max_zoom\":\"3\",\"override_users_location_zoom_levels\":\"\",\"map_min_zoom\":\"21\",\"sl_stroke_color\":\"\",\"sl_stroke_opacity\":\"\",\"sl_fill_color\":\"\",\"sl_fill_opacity\":\"\",\"automatically_pan_to_users_location\":0,\"override_users_location_zoom_level\":0,\"click_open_link\":2,\"hide_point_of_interest\":false,\"wpgmza_auto_night\":0,\"transport_layer\":0,\"iw_primary_color\":\"2A3744\",\"iw_accent_color\":\"252F3A\",\"iw_text_color\":\"FFFFFF\",\"wpgmza_iw_type\":\"0\",\"list_markers_by\":\"0\",\"push_in_map\":\"\",\"push_in_map_placement\":\"9\",\"wpgmza_push_in_map_width\":\"\",\"wpgmza_push_in_map_height\":\"\",\"wpgmza_theme_data\":\"\",\"upload_default_ul_marker\":\"\",\"upload_default_sl_marker\":\"\",\"shortcodeAttributes\":{\"id\":\"269\"}}}' data-map-id='269' data-shortcode-attributes='{\"id\":\"269\"}'> <\/div>\r\n            \r\n               \r\n        \n","protected":false},"excerpt":{"rendered":"<p>El evento se celebra los primeros domingos de cada mes, de 9:00 a 14:00 horas, en el Gran Riurau de Jes\u00fas Pobre (Alicante). En esta feria podr\u00e1 encontrar gran cantidad de objetos de coleccionismo y decoraci\u00f3n como muebles, espejos, relojes, piezas de cer\u00e1mica, cristal o porcelana, esculturas, bronces, l\u00e1mparas, monedas, objetos vintage, retro, industrial, antig\u00fcedades y un largo etc&#8230; Ampliar informaci\u00f3n Localizaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":37750,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5361],"tags":[5335],"class_list":["post-37747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visitas","tag-jesus-pobre-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSTA BLANCA UP - &quot;Feria de Coleccionistas y Brocanters&quot; de Jes\u00fas Pobre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSTA BLANCA UP - &quot;Feria de Coleccionistas y Brocanters&quot; de Jes\u00fas Pobre\" \/>\n<meta property=\"og:description\" content=\"El evento se celebra los primeros domingos de cada mes, de 9:00 a 14:00 horas, en el Gran Riurau de Jes\u00fas Pobre (Alicante). En esta feria podr\u00e1 encontrar gran cantidad de objetos de coleccionismo y decoraci\u00f3n como muebles, espejos, relojes, piezas de cer\u00e1mica, cristal o porcelana, esculturas, bronces, l\u00e1mparas, monedas, objetos vintage, retro, industrial, antig\u00fcedades y un largo etc&#8230; Ampliar informaci\u00f3n Localizaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-27T08:04:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-03T09:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/\"},\"author\":{\"name\":\"jas_admin\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\"},\"headline\":\"\u00abFeria de Coleccionistas y Brocanters\u00bb de Jes\u00fas Pobre\",\"datePublished\":\"2019-11-27T08:04:13+00:00\",\"dateModified\":\"2021-06-03T09:44:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/feria-brocanters-jesus-pobre.jpg\",\"keywords\":[\"Jes\u00fas Pobre\"],\"articleSection\":[\"Visitas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/\",\"name\":\"COSTA BLANCA UP - \\\"Feria de Coleccionistas y Brocanters\\\" de Jes\u00fas Pobre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/feria-brocanters-jesus-pobre.jpg\",\"datePublished\":\"2019-11-27T08:04:13+00:00\",\"dateModified\":\"2021-06-03T09:44:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/feria-brocanters-jesus-pobre.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/feria-brocanters-jesus-pobre.jpg\",\"width\":800,\"height\":434,\"caption\":\"Feria de Coleccionistas y Brocanters de Jes\u00fas Pobre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abFeria de Coleccionistas y Brocanters\u00bb de Jes\u00fas Pobre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\",\"name\":\"jas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"caption\":\"jas_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSTA BLANCA UP - \"Feria de Coleccionistas y Brocanters\" de Jes\u00fas Pobre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/","og_locale":"es_ES","og_type":"article","og_title":"COSTA BLANCA UP - \"Feria de Coleccionistas y Brocanters\" de Jes\u00fas Pobre","og_description":"El evento se celebra los primeros domingos de cada mes, de 9:00 a 14:00 horas, en el Gran Riurau de Jes\u00fas Pobre (Alicante). En esta feria podr\u00e1 encontrar gran cantidad de objetos de coleccionismo y decoraci\u00f3n como muebles, espejos, relojes, piezas de cer\u00e1mica, cristal o porcelana, esculturas, bronces, l\u00e1mparas, monedas, objetos vintage, retro, industrial, antig\u00fcedades y un largo etc&#8230; Ampliar informaci\u00f3n Localizaci\u00f3n","og_url":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/","og_site_name":"COSTA BLANCA UP","article_published_time":"2019-11-27T08:04:13+00:00","article_modified_time":"2021-06-03T09:44:28+00:00","og_image":[{"width":800,"height":434,"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg","type":"image\/jpeg"}],"author":"jas_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jas_admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#article","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/"},"author":{"name":"jas_admin","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489"},"headline":"\u00abFeria de Coleccionistas y Brocanters\u00bb de Jes\u00fas Pobre","datePublished":"2019-11-27T08:04:13+00:00","dateModified":"2021-06-03T09:44:28+00:00","mainEntityOfPage":{"@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"image":{"@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg","keywords":["Jes\u00fas Pobre"],"articleSection":["Visitas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/","url":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/","name":"COSTA BLANCA UP - \"Feria de Coleccionistas y Brocanters\" de Jes\u00fas Pobre","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg","datePublished":"2019-11-27T08:04:13+00:00","dateModified":"2021-06-03T09:44:28+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/11\/feria-brocanters-jesus-pobre.jpg","width":800,"height":434,"caption":"Feria de Coleccionistas y Brocanters de Jes\u00fas Pobre"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/feria-de-coleccionistas-y-brocanters-de-jesus-pobre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abFeria de Coleccionistas y Brocanters\u00bb de Jes\u00fas Pobre"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489","name":"jas_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","caption":"jas_admin"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/37747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/comments?post=37747"}],"version-history":[{"count":2,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/37747\/revisions"}],"predecessor-version":[{"id":48938,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/37747\/revisions\/48938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media\/37750"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=37747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/categories?post=37747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/tags?post=37747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}