{"id":41517,"date":"2020-02-10T12:42:12","date_gmt":"2020-02-10T11:42:12","guid":{"rendered":"https:\/\/costablancaup.com\/?p=41517"},"modified":"2020-02-23T11:20:05","modified_gmt":"2020-02-23T10:20:05","slug":"carnaval-en-la-costa-blanca","status":"publish","type":"post","link":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/","title":{"rendered":"Carnaval en la Costa Blanca"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg\" alt=\"Carnaval Alicante 2020\" width=\"800\" height=\"555\" class=\"aligncenter size-full wp-image-25780\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante-300x208.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante-768x533.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante-400x278.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><br \/>\n<\/p>\n<div class=\"piefoto\">Por alicante.es<\/div>\n<p><\/p>\n<h2>Durante estas fechas las calles de las ciudades se llenar\u00e1n de diversi\u00f3n, m\u00fasica, disfraces, desfiles, animaci\u00f3n y otras actividades para celebrar esta esperada fiesta.<\/h2>\n<p>Estas son algunas de los localidades que celebrar\u00e1n Carnaval durante los pr\u00f3ximos d\u00edas:<\/p>\n<h4>Alicante (del 20 de febrero al 1 de marzo)<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-alicante-2020.jpg\" alt=\"Carnaval 2020: programa Alicante\" width=\"800\" height=\"628\" class=\"aligncenter size-full wp-image-41520\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-alicante-2020.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-alicante-2020-300x236.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-alicante-2020-768x603.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-alicante-2020-400x314.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Ayora (del 21 al 29 de febrero)<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-ayora-programa.jpg\" alt=\"Carnaval 2020: programa Ayora\" width=\"800\" height=\"1039\" class=\"aligncenter size-full wp-image-41524\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-ayora-programa.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-ayora-programa-231x300.jpg 231w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-ayora-programa-788x1024.jpg 788w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-ayora-programa-768x997.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-ayora-programa-400x520.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Calpe (22 de febrero)<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-calpe-programa.jpg\" alt=\"Carnaval 2020: programa Calpe\" width=\"1024\" height=\"1479\" class=\"aligncenter size-full wp-image-41532\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-calpe-programa.jpg 1024w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-calpe-programa-208x300.jpg 208w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-calpe-programa-709x1024.jpg 709w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-calpe-programa-768x1109.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-calpe-programa-400x578.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Ibi (22 de febrero)<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-ibi-2020-programa.jpg\" alt=\"Carnaval 2020: programa Ibi\" width=\"800\" height=\"1000\" class=\"aligncenter size-full wp-image-41536\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-ibi-2020-programa.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-ibi-2020-programa-240x300.jpg 240w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-ibi-2020-programa-768x960.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-ibi-2020-programa-400x500.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Pego (17 al 29 de febrero)<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-pego-programa.jpg\" alt=\"Carnaval 2020: programa Pego\" width=\"800\" height=\"1647\" class=\"aligncenter size-full wp-image-41540\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-pego-programa.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-pego-programa-146x300.jpg 146w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-pego-programa-497x1024.jpg 497w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-pego-programa-768x1581.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-pego-programa-746x1536.jpg 746w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-2020-pego-programa-400x824.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Russafa (Valencia) (15 de febrero)<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-russafa-2020-programa.jpg\" alt=\"Carnaval 2020: programa Russafa (Valencia)\" width=\"800\" height=\"869\" class=\"aligncenter size-full wp-image-41544\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-russafa-2020-programa.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-russafa-2020-programa-276x300.jpg 276w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-russafa-2020-programa-768x834.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-russafa-2020-programa-400x435.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Torrevieja (31 de enero al 16 de febrero)<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-torrevieja-2020-programa.jpg\" alt=\"Carnaval 2020: programa Torrevieja\" width=\"1024\" height=\"811\" class=\"aligncenter size-full wp-image-41528\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-torrevieja-2020-programa.jpg 1024w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-torrevieja-2020-programa-300x238.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-torrevieja-2020-programa-768x608.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/carnaval-torrevieja-2020-programa-400x317.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante estas fechas las calles de las ciudades se llenar\u00e1n de diversi\u00f3n, m\u00fasica, disfraces, desfiles, animaci\u00f3n y otras actividades para celebrar esta esperada fiesta. Estas son algunas de los localidades que celebrar\u00e1n Carnaval durante los pr\u00f3ximos d\u00edas: Alicante (del 20 de febrero al 1 de marzo) &nbsp; Ayora (del 21 al 29 de febrero) &nbsp; Calpe (22 de febrero) &nbsp; Ibi (22 de febrero) &nbsp; Pego (17 al 29 de febrero) &nbsp; Russafa (Valencia) (15 de febrero) &nbsp; Torrevieja (31 de enero al 16 de febrero)<\/p>\n","protected":false},"author":1,"featured_media":25780,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5016],"tags":[5070,5396,5071,5374,5864,5130,5073],"class_list":["post-41517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas-eventos","tag-alicante-es","tag-ayora-es","tag-calpe-es","tag-ibi-es","tag-pego","tag-torrevieja-es","tag-valencia-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSTA BLANCA UP - Carnaval en la Costa Blanca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSTA BLANCA UP - Carnaval en la Costa Blanca\" \/>\n<meta property=\"og:description\" content=\"Durante estas fechas las calles de las ciudades se llenar\u00e1n de diversi\u00f3n, m\u00fasica, disfraces, desfiles, animaci\u00f3n y otras actividades para celebrar esta esperada fiesta. Estas son algunas de los localidades que celebrar\u00e1n Carnaval durante los pr\u00f3ximos d\u00edas: Alicante (del 20 de febrero al 1 de marzo) &nbsp; Ayora (del 21 al 29 de febrero) &nbsp; Calpe (22 de febrero) &nbsp; Ibi (22 de febrero) &nbsp; Pego (17 al 29 de febrero) &nbsp; Russafa (Valencia) (15 de febrero) &nbsp; Torrevieja (31 de enero al 16 de febrero)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-10T11:42:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-23T10:20:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jas_admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/\"},\"author\":{\"name\":\"jas_admin\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\"},\"headline\":\"Carnaval en la Costa Blanca\",\"datePublished\":\"2020-02-10T11:42:12+00:00\",\"dateModified\":\"2020-02-23T10:20:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/\"},\"wordCount\":92,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/carnaval-2019-alicante.jpg\",\"keywords\":[\"Alicante\",\"Ayora\",\"Calpe\",\"Ibi\",\"Pego\",\"Torrevieja\",\"Valencia\"],\"articleSection\":[\"Fiestas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/\",\"name\":\"COSTA BLANCA UP - Carnaval en la Costa Blanca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/carnaval-2019-alicante.jpg\",\"datePublished\":\"2020-02-10T11:42:12+00:00\",\"dateModified\":\"2020-02-23T10:20:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/carnaval-2019-alicante.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/carnaval-2019-alicante.jpg\",\"width\":800,\"height\":555,\"caption\":\"Carnaval Alicante 2019\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/carnaval-en-la-costa-blanca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carnaval en la Costa Blanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\",\"name\":\"jas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"caption\":\"jas_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSTA BLANCA UP - Carnaval en la Costa Blanca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/","og_locale":"es_ES","og_type":"article","og_title":"COSTA BLANCA UP - Carnaval en la Costa Blanca","og_description":"Durante estas fechas las calles de las ciudades se llenar\u00e1n de diversi\u00f3n, m\u00fasica, disfraces, desfiles, animaci\u00f3n y otras actividades para celebrar esta esperada fiesta. Estas son algunas de los localidades que celebrar\u00e1n Carnaval durante los pr\u00f3ximos d\u00edas: Alicante (del 20 de febrero al 1 de marzo) &nbsp; Ayora (del 21 al 29 de febrero) &nbsp; Calpe (22 de febrero) &nbsp; Ibi (22 de febrero) &nbsp; Pego (17 al 29 de febrero) &nbsp; Russafa (Valencia) (15 de febrero) &nbsp; Torrevieja (31 de enero al 16 de febrero)","og_url":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/","og_site_name":"COSTA BLANCA UP","article_published_time":"2020-02-10T11:42:12+00:00","article_modified_time":"2020-02-23T10:20:05+00:00","og_image":[{"width":800,"height":555,"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg","type":"image\/jpeg"}],"author":"jas_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jas_admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#article","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/"},"author":{"name":"jas_admin","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489"},"headline":"Carnaval en la Costa Blanca","datePublished":"2020-02-10T11:42:12+00:00","dateModified":"2020-02-23T10:20:05+00:00","mainEntityOfPage":{"@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/"},"wordCount":92,"commentCount":0,"publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"image":{"@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg","keywords":["Alicante","Ayora","Calpe","Ibi","Pego","Torrevieja","Valencia"],"articleSection":["Fiestas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/","url":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/","name":"COSTA BLANCA UP - Carnaval en la Costa Blanca","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg","datePublished":"2020-02-10T11:42:12+00:00","dateModified":"2020-02-23T10:20:05+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2019\/02\/carnaval-2019-alicante.jpg","width":800,"height":555,"caption":"Carnaval Alicante 2019"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/carnaval-en-la-costa-blanca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Carnaval en la Costa Blanca"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489","name":"jas_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","caption":"jas_admin"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/41517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/comments?post=41517"}],"version-history":[{"count":11,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/41517\/revisions"}],"predecessor-version":[{"id":41555,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/41517\/revisions\/41555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media\/25780"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=41517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/categories?post=41517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/tags?post=41517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}