{"id":41561,"date":"2020-02-11T09:58:34","date_gmt":"2020-02-11T08:58:34","guid":{"rendered":"https:\/\/costablancaup.com\/?p=41561"},"modified":"2020-02-11T10:01:25","modified_gmt":"2020-02-11T09:01:25","slug":"feria-del-dia-del-villazgo-2020-en-pinoso","status":"publish","type":"post","link":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/","title":{"rendered":"Feria del \u00abD\u00eda del Villazgo 2020\u00bb en Pinoso"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg\" alt=\"D\u00eda del Villazgo 2020 en Pinoso\" width=\"800\" height=\"500\" class=\"aligncenter size-full wp-image-41562\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-300x188.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-768x480.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-400x250.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><br \/>\n<\/p>\n<div class=\"piefoto\">Por conocer.pinoso.org<\/div>\n<p><\/p>\n<h2>El domingo 16 de febrero se celebra el \u00abD\u00eda del Villazgo\u00bb en la localidad alicantina de Pinoso, conmemorando la concesi\u00f3n a la poblaci\u00f3n de Pinoso del t\u00edtulo de villa independiente en el a\u00f1o 1826.<\/h2>\n<p>Para celebrar el d\u00eda se lleva a cabo una \u00abMuestra de Pinoso antiguo\u00bb, en la que se recuerdan viejos oficios y costumbres. <\/p>\n<p>Tambi\u00e9n se organiza una Feria de degustaci\u00f3n y venta de productos artesanales y gastron\u00f3micos. Y todo ello amenizado con m\u00fasica tradicional y bailes t\u00edpicos.<\/p>\n<h3>Programa<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-2020-programa.jpg\" alt=\"D\u00eda del Villazgo Pinoso 2020: programa\" width=\"800\" height=\"682\" class=\"aligncenter size-full wp-image-41567\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-2020-programa.jpg 800w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-2020-programa-300x256.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-2020-programa-768x655.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso-2020-programa-400x341.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Localizaci\u00f3n<\/h3>\n\r\n            \r\n            \r\n            \r\n            <a name='map298'><\/a>\r\n            \r\n            \r\n            \r\n            \r\n            <div class=\"wpgmza_map \"  id=\"wpgmza_map_298\" style=\"display:block; overflow:auto; width:100%; height:400px; float:left;\" data-settings='{\"id\":\"298\",\"map_title\":\"Ayuntamiento de Pinoso\",\"map_width\":\"100\",\"map_height\":\"400\",\"map_start_lat\":\"38.403037\",\"map_start_lng\":\"-1.042517\",\"map_start_location\":\"38.403037116843706,-1.0425165333862951\",\"map_start_zoom\":\"15\",\"default_marker\":\"0\",\"type\":\"1\",\"alignment\":\"1\",\"directions_enabled\":\"0\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"1\",\"dbox_width\":\"100\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"\\\\%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"0\",\"ugm_access\":\"0\",\"order_markers_by\":\"1\",\"order_markers_choice\":\"2\",\"show_user_location\":\"2\",\"default_to\":\"\",\"other_settings\":{\"store_locator_style\":\"legacy\",\"wpgmza_store_locator_radius_style\":\"legacy\",\"directions_box_style\":\"modern\",\"wpgmza_dbox_width_type\":\"%\",\"map_max_zoom\":\"3\",\"map_min_zoom\":\"21\",\"sl_stroke_color\":\"\",\"sl_stroke_opacity\":\"\",\"sl_fill_color\":\"\",\"sl_fill_opacity\":\"\",\"automatically_pan_to_users_location\":0,\"override_users_location_zoom_level\":0,\"click_open_link\":2,\"hide_point_of_interest\":false,\"wpgmza_auto_night\":0,\"transport_layer\":0,\"iw_primary_color\":\"2A3744\",\"iw_accent_color\":\"252F3A\",\"iw_text_color\":\"FFFFFF\",\"wpgmza_iw_type\":\"0\",\"list_markers_by\":\"0\",\"push_in_map\":\"\",\"push_in_map_placement\":\"9\",\"wpgmza_push_in_map_width\":\"\",\"wpgmza_push_in_map_height\":\"\",\"wpgmza_theme_data\":\"\",\"upload_default_ul_marker\":\"\",\"upload_default_sl_marker\":\"\",\"shortcodeAttributes\":{\"id\":\"298\"}}}' data-map-id='298' data-shortcode-attributes='{\"id\":\"298\"}'> <\/div>\r\n            \r\n               \r\n        \n","protected":false},"excerpt":{"rendered":"<p>El domingo 16 de febrero se celebra el \u00abD\u00eda del Villazgo\u00bb en la localidad alicantina de Pinoso, conmemorando la concesi\u00f3n a la poblaci\u00f3n de Pinoso del t\u00edtulo de villa independiente en el a\u00f1o 1826. Para celebrar el d\u00eda se lleva a cabo una \u00abMuestra de Pinoso antiguo\u00bb, en la que se recuerdan viejos oficios y costumbres. Tambi\u00e9n se organiza una Feria de degustaci\u00f3n y venta de productos artesanales y gastron\u00f3micos. Y todo ello amenizado con m\u00fasica tradicional y bailes t\u00edpicos. Programa Localizaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":41562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5015],"tags":[6361],"class_list":["post-41561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-culturales","tag-pinoso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSTA BLANCA UP - Feria del &quot;D\u00eda del Villazgo 2020&quot; en Pinoso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSTA BLANCA UP - Feria del &quot;D\u00eda del Villazgo 2020&quot; en Pinoso\" \/>\n<meta property=\"og:description\" content=\"El domingo 16 de febrero se celebra el \u00abD\u00eda del Villazgo\u00bb en la localidad alicantina de Pinoso, conmemorando la concesi\u00f3n a la poblaci\u00f3n de Pinoso del t\u00edtulo de villa independiente en el a\u00f1o 1826. Para celebrar el d\u00eda se lleva a cabo una \u00abMuestra de Pinoso antiguo\u00bb, en la que se recuerdan viejos oficios y costumbres. Tambi\u00e9n se organiza una Feria de degustaci\u00f3n y venta de productos artesanales y gastron\u00f3micos. Y todo ello amenizado con m\u00fasica tradicional y bailes t\u00edpicos. Programa Localizaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-11T08:58:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-11T09:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/\"},\"author\":{\"name\":\"jas_admin\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\"},\"headline\":\"Feria del \u00abD\u00eda del Villazgo 2020\u00bb en Pinoso\",\"datePublished\":\"2020-02-11T08:58:34+00:00\",\"dateModified\":\"2020-02-11T09:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/\"},\"wordCount\":108,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/dia-villazgo-pinoso.jpg\",\"keywords\":[\"Pinoso\"],\"articleSection\":[\"Eventos culturales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/\",\"name\":\"COSTA BLANCA UP - Feria del \\\"D\u00eda del Villazgo 2020\\\" en Pinoso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/dia-villazgo-pinoso.jpg\",\"datePublished\":\"2020-02-11T08:58:34+00:00\",\"dateModified\":\"2020-02-11T09:01:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/dia-villazgo-pinoso.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/dia-villazgo-pinoso.jpg\",\"width\":800,\"height\":500,\"caption\":\"D\u00eda del Villazgo 2020 en Pinoso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/feria-del-dia-del-villazgo-2020-en-pinoso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feria del \u00abD\u00eda del Villazgo 2020\u00bb en Pinoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\",\"name\":\"jas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"caption\":\"jas_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSTA BLANCA UP - Feria del \"D\u00eda del Villazgo 2020\" en Pinoso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/","og_locale":"es_ES","og_type":"article","og_title":"COSTA BLANCA UP - Feria del \"D\u00eda del Villazgo 2020\" en Pinoso","og_description":"El domingo 16 de febrero se celebra el \u00abD\u00eda del Villazgo\u00bb en la localidad alicantina de Pinoso, conmemorando la concesi\u00f3n a la poblaci\u00f3n de Pinoso del t\u00edtulo de villa independiente en el a\u00f1o 1826. Para celebrar el d\u00eda se lleva a cabo una \u00abMuestra de Pinoso antiguo\u00bb, en la que se recuerdan viejos oficios y costumbres. Tambi\u00e9n se organiza una Feria de degustaci\u00f3n y venta de productos artesanales y gastron\u00f3micos. Y todo ello amenizado con m\u00fasica tradicional y bailes t\u00edpicos. Programa Localizaci\u00f3n","og_url":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/","og_site_name":"COSTA BLANCA UP","article_published_time":"2020-02-11T08:58:34+00:00","article_modified_time":"2020-02-11T09:01:25+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg","type":"image\/jpeg"}],"author":"jas_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jas_admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#article","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/"},"author":{"name":"jas_admin","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489"},"headline":"Feria del \u00abD\u00eda del Villazgo 2020\u00bb en Pinoso","datePublished":"2020-02-11T08:58:34+00:00","dateModified":"2020-02-11T09:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/"},"wordCount":108,"commentCount":0,"publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"image":{"@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg","keywords":["Pinoso"],"articleSection":["Eventos culturales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/","url":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/","name":"COSTA BLANCA UP - Feria del \"D\u00eda del Villazgo 2020\" en Pinoso","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg","datePublished":"2020-02-11T08:58:34+00:00","dateModified":"2020-02-11T09:01:25+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2020\/02\/dia-villazgo-pinoso.jpg","width":800,"height":500,"caption":"D\u00eda del Villazgo 2020 en Pinoso"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/feria-del-dia-del-villazgo-2020-en-pinoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Feria del \u00abD\u00eda del Villazgo 2020\u00bb en Pinoso"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489","name":"jas_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","caption":"jas_admin"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/41561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/comments?post=41561"}],"version-history":[{"count":6,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/41561\/revisions"}],"predecessor-version":[{"id":41606,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/41561\/revisions\/41606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media\/41562"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=41561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/categories?post=41561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/tags?post=41561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}