{"id":50073,"date":"2021-10-01T10:19:30","date_gmt":"2021-10-01T08:19:30","guid":{"rendered":"https:\/\/costablancaup.com\/?p=50073"},"modified":"2021-10-01T10:23:45","modified_gmt":"2021-10-01T08:23:45","slug":"alicante-ciudad-del-arroz-2021","status":"publish","type":"post","link":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/","title":{"rendered":"\u00abAlicante Ciudad del arroz\u00bb 2021"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-50077\" src=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg\" alt=\"Alicante Ciudad del arroz 2021\" width=\"1024\" height=\"373\" srcset=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg 1024w, https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021-300x109.jpg 300w, https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021-768x280.jpg 768w, https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021-400x146.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<\/p>\n<div class=\"piefoto\">Por jornadasalicanteciudaddelarroz.com<\/div>\n<p>\n<h2>El evento gastron\u00f3mico se celebrar\u00e1 del 1 al 29 de octubre en la ciudad de Alicante.<\/h2>\n<p>Se trata de rendir un homenaje al producto estrella de la gastronom\u00eda alicantina: el arroz, desarrollando una serie de actividades que contribuyan a la promoci\u00f3n de los valores de Alicante como destino id\u00f3neo para visitantes.<\/p>\n<p>Durante esos d\u00edas, en 30 diferentes restaurantes de la ciudad, se ofrecer\u00e1n men\u00fas especiales con arroz alicantino como plato principal, con productos aut\u00f3ctonos y de kil\u00f3metro 0, y dulces t\u00edpicos de Alicante.<\/p>\n<p class=\"tickets\"><a title=\"Ampliar informaci\u00f3n y reservar\" href=\"https:\/\/www.jornadasalicanteciudaddelarroz.com\/restaurantes.php\" target=\"_blank\" rel=\"noopener noreferrer\">Ampliar informaci\u00f3n y reservar<\/a><\/p>\n<h3>V\u00eddeo promocional<\/h3>\n<p><iframe loading=\"lazy\" title=\"Jornadas Alicante Ciudad del Arroz\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/VxXulspk8Dw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento gastron\u00f3mico se celebrar\u00e1 del 1 al 29 de octubre en la ciudad de Alicante. Se trata de rendir un homenaje al producto estrella de la gastronom\u00eda alicantina: el arroz, desarrollando una serie de actividades que contribuyan a la promoci\u00f3n de los valores de Alicante como destino id\u00f3neo para visitantes. Durante esos d\u00edas, en 30 diferentes restaurantes de la ciudad, se ofrecer\u00e1n men\u00fas especiales con arroz alicantino como plato principal, con productos aut\u00f3ctonos y de kil\u00f3metro 0, y dulces t\u00edpicos de Alicante. Ampliar informaci\u00f3n y reservar V\u00eddeo promocional<\/p>\n","protected":false},"author":1,"featured_media":50077,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5015,6533],"tags":[5070],"class_list":["post-50073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-culturales","category-ocio-y-cultura","tag-alicante-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSTA BLANCA UP - &quot;Alicante Ciudad del arroz&quot; 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSTA BLANCA UP - &quot;Alicante Ciudad del arroz&quot; 2021\" \/>\n<meta property=\"og:description\" content=\"El evento gastron\u00f3mico se celebrar\u00e1 del 1 al 29 de octubre en la ciudad de Alicante. Se trata de rendir un homenaje al producto estrella de la gastronom\u00eda alicantina: el arroz, desarrollando una serie de actividades que contribuyan a la promoci\u00f3n de los valores de Alicante como destino id\u00f3neo para visitantes. Durante esos d\u00edas, en 30 diferentes restaurantes de la ciudad, se ofrecer\u00e1n men\u00fas especiales con arroz alicantino como plato principal, con productos aut\u00f3ctonos y de kil\u00f3metro 0, y dulces t\u00edpicos de Alicante. Ampliar informaci\u00f3n y reservar V\u00eddeo promocional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"COSTA BLANCA UP\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T08:19:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-01T08:23:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jas_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jas_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/\"},\"author\":{\"name\":\"jas_admin\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\"},\"headline\":\"\u00abAlicante Ciudad del arroz\u00bb 2021\",\"datePublished\":\"2021-10-01T08:19:30+00:00\",\"dateModified\":\"2021-10-01T08:23:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/\"},\"wordCount\":111,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/alicante-ciudad-del-arroz-2021.jpg\",\"keywords\":[\"Alicante\"],\"articleSection\":[\"Eventos culturales\",\"Ocio y cultura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/\",\"name\":\"COSTA BLANCA UP - \\\"Alicante Ciudad del arroz\\\" 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/alicante-ciudad-del-arroz-2021.jpg\",\"datePublished\":\"2021-10-01T08:19:30+00:00\",\"dateModified\":\"2021-10-01T08:23:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/alicante-ciudad-del-arroz-2021.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/alicante-ciudad-del-arroz-2021.jpg\",\"width\":1024,\"height\":373,\"caption\":\"Alicante Ciudad del arroz 2021\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/alicante-ciudad-del-arroz-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abAlicante Ciudad del arroz\u00bb 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"name\":\"COSTA BLANCA UP\",\"description\":\"Costa Blanca Events and Agenda\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Up\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"contentUrl\":\"https:\\\/\\\/costablancaup.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/titulo_web-1.png\",\"width\":1973,\"height\":303,\"caption\":\"Costa Blanca Up\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costablancaup.com\\\/es\\\/#\\\/schema\\\/person\\\/a4a0ee1ba74dae33c5d59d6279cd9489\",\"name\":\"jas_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g\",\"caption\":\"jas_admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSTA BLANCA UP - \"Alicante Ciudad del arroz\" 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/","og_locale":"es_ES","og_type":"article","og_title":"COSTA BLANCA UP - \"Alicante Ciudad del arroz\" 2021","og_description":"El evento gastron\u00f3mico se celebrar\u00e1 del 1 al 29 de octubre en la ciudad de Alicante. Se trata de rendir un homenaje al producto estrella de la gastronom\u00eda alicantina: el arroz, desarrollando una serie de actividades que contribuyan a la promoci\u00f3n de los valores de Alicante como destino id\u00f3neo para visitantes. Durante esos d\u00edas, en 30 diferentes restaurantes de la ciudad, se ofrecer\u00e1n men\u00fas especiales con arroz alicantino como plato principal, con productos aut\u00f3ctonos y de kil\u00f3metro 0, y dulces t\u00edpicos de Alicante. Ampliar informaci\u00f3n y reservar V\u00eddeo promocional","og_url":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/","og_site_name":"COSTA BLANCA UP","article_published_time":"2021-10-01T08:19:30+00:00","article_modified_time":"2021-10-01T08:23:45+00:00","og_image":[{"width":1024,"height":373,"url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg","type":"image\/jpeg"}],"author":"jas_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jas_admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#article","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/"},"author":{"name":"jas_admin","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489"},"headline":"\u00abAlicante Ciudad del arroz\u00bb 2021","datePublished":"2021-10-01T08:19:30+00:00","dateModified":"2021-10-01T08:23:45+00:00","mainEntityOfPage":{"@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/"},"wordCount":111,"commentCount":0,"publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"image":{"@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg","keywords":["Alicante"],"articleSection":["Eventos culturales","Ocio y cultura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/","url":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/","name":"COSTA BLANCA UP - \"Alicante Ciudad del arroz\" 2021","isPartOf":{"@id":"https:\/\/costablancaup.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#primaryimage"},"image":{"@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg","datePublished":"2021-10-01T08:19:30+00:00","dateModified":"2021-10-01T08:23:45+00:00","breadcrumb":{"@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#primaryimage","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2021\/10\/alicante-ciudad-del-arroz-2021.jpg","width":1024,"height":373,"caption":"Alicante Ciudad del arroz 2021"},{"@type":"BreadcrumbList","@id":"https:\/\/costablancaup.com\/es\/alicante-ciudad-del-arroz-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancaup.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abAlicante Ciudad del arroz\u00bb 2021"}]},{"@type":"WebSite","@id":"https:\/\/costablancaup.com\/es\/#website","url":"https:\/\/costablancaup.com\/es\/","name":"COSTA BLANCA UP","description":"Costa Blanca Events and Agenda","publisher":{"@id":"https:\/\/costablancaup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancaup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancaup.com\/es\/#organization","name":"Costa Blanca Up","url":"https:\/\/costablancaup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","contentUrl":"https:\/\/costablancaup.com\/wp-content\/uploads\/2018\/07\/titulo_web-1.png","width":1973,"height":303,"caption":"Costa Blanca Up"},"image":{"@id":"https:\/\/costablancaup.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/costablancaup.com\/es\/#\/schema\/person\/a4a0ee1ba74dae33c5d59d6279cd9489","name":"jas_admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5a1282fae1020d8b4f7a1b95dac31c3c08f7dfd0a06b2ba5aa24fa117526f78?s=96&d=mm&r=g","caption":"jas_admin"}}]}},"_links":{"self":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/50073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/comments?post=50073"}],"version-history":[{"count":5,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/50073\/revisions"}],"predecessor-version":[{"id":50082,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/posts\/50073\/revisions\/50082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media\/50077"}],"wp:attachment":[{"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/media?parent=50073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/categories?post=50073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costablancaup.com\/es\/wp-json\/wp\/v2\/tags?post=50073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}